{"id":4628,"date":"2025-01-17T09:48:05","date_gmt":"2025-01-17T09:48:05","guid":{"rendered":"https:\/\/jackpotgenius.ai\/lottery-news\/numeros-ganadores-de-la-superenalotto-del-16-de-enero-de-2025\/"},"modified":"2025-01-17T09:48:05","modified_gmt":"2025-01-17T09:48:05","slug":"numeros-ganadores-de-la-superenalotto-del-16-de-enero-de-2025","status":"publish","type":"lottery-news","link":"https:\/\/jackpotgenius.ai\/es\/lottery-news\/numeros-ganadores-de-la-superenalotto-del-16-de-enero-de-2025\/","title":{"rendered":"N\u00fameros ganadores de la SuperEnalotto del 16 de enero de 2025"},"content":{"rendered":"<p>Muchos han acudido esta tarde a esperar el gran \u00ab6\u00bb, el \u00ab5+\u00bb y los importantes resultados de los n\u00fameros SuperStar. Emerge en importancia un notable \u00ab5\u00bb y el bote de 60 millones. Nos encontramos en la \u00faltima mitad del mes, similar a la columna derecha de los calendarios con dos columnas. El calendario, un invento extraordinario, nos devuelve a enero, llamado as\u00ed por Jano, el dios de dos caras que pod\u00eda mirar hacia delante y hacia atr\u00e1s. Atr\u00e1s quedan las \u00ab6\u00bb victorias del a\u00f1o pasado, el ya lejano 2024, con s\u00f3lo dos victorias frente a las cuatro de 2023. \u00bfQu\u00e9 nos deparar\u00e1 2025? So\u00f1emos un poco, lo necesitamos. \u00bfO no? Descubramos la combinaci\u00f3n ganadora del sorteo n\u00famero 9 de la SuperEnalotto del jueves 16 de enero: 31, 38, 59, 69, 72, 88, Jolly 64, SuperStar 73.<\/p>\n<p>SuperEnalotto, Ganancias de hoy<br \/>\nEl \u00ab5\u00bb ha hecho una declaraci\u00f3n impresionante esta noche, admit\u00e1moslo, trayendo buenas noticias mientras que el \u00ab6\u00bb y el \u00ab5+\u00bb siguen siendo esquivos. Esta noche, tres afortunados jugadores han acertado el \u00ab5\u00bb y han ganado 58.905,23 euros cada uno. Los ganadores fueron BOVEZZO (BS) en el BAR TABACCHI de VIA VERDI, 58, AIRUNO (LC) en el BAR PALMA de VIA STATALE, 27, y GIULIANOVA (TE) en la TABACCHERIA DEL CORSO de VIA NAZARIO SAURO, 110. En el n\u00famero SuperStar, sesenta y ocho jugadores ganaron 3.398 euros cada uno con la \u00ab3 Estrella\u00bb. La bolsa de premios para el pr\u00f3ximo sorteo asciende a la friolera de 60 millones de euros. \u00a1Guau!<\/p>\n<p>Pr\u00f3ximo sorteo de la SuperEnalotto<br \/>\n\u00bfTe gustar\u00eda intentar ganar el premio gordo en el pr\u00f3ximo sorteo de la SuperEnalotto del viernes 17 de enero? Tienes varias opciones para jugar tu boleto: visitar un Punto de Venta autorizado, utilizar uno de los sitios web aprobados o confiar en la App oficial de la SuperEnalotto. Recuerda que los sorteos de la SuperEnalotto se celebran semanalmente los martes, jueves y s\u00e1bados a las 20:00 h. Desde 2023, se celebra un cuarto sorteo el viernes a la misma hora para ayudar a financiar un programa de apoyo a las zonas afectadas por las inundaciones de Emilia Roma\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchos han acudido esta tarde a esperar el gran \u00ab6\u00bb, el \u00ab5+\u00bb y los importantes resultados de los n\u00fameros SuperStar. Emerge en importancia un notable \u00ab5\u00bb y el bote de 60 millones. Nos encontramos en la \u00faltima mitad del mes, similar a la columna derecha de los calendarios con dos columnas. El calendario, un invento [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","tags":[308,491],"lottery-name":[515],"class_list":["post-4628","lottery-news","type-lottery-news","status-publish","hentry","tag-draw-result","tag-superenalotto","lottery-name-superenalotto"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/jackpotgenius.ai\/es\/wp-json\/wp\/v2\/lottery-news\/4628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jackpotgenius.ai\/es\/wp-json\/wp\/v2\/lottery-news"}],"about":[{"href":"https:\/\/jackpotgenius.ai\/es\/wp-json\/wp\/v2\/types\/lottery-news"}],"replies":[{"embeddable":true,"href":"https:\/\/jackpotgenius.ai\/es\/wp-json\/wp\/v2\/comments?post=4628"}],"wp:attachment":[{"href":"https:\/\/jackpotgenius.ai\/es\/wp-json\/wp\/v2\/media?parent=4628"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jackpotgenius.ai\/es\/wp-json\/wp\/v2\/tags?post=4628"},{"taxonomy":"lottery-name","embeddable":true,"href":"https:\/\/jackpotgenius.ai\/es\/wp-json\/wp\/v2\/lottery-name?post=4628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}